{"id":36,"date":"2021-09-03T01:02:51","date_gmt":"2021-09-03T01:02:51","guid":{"rendered":"http:\/\/wangjianhao.cn\/?page_id=19"},"modified":"2026-01-27T02:43:35","modified_gmt":"2026-01-27T02:43:35","slug":"uber-uns","status":"publish","type":"page","link":"https:\/\/hsmagnet.com\/de\/about-us\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"<div style=\"background-image:url(&apos;https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/building.webp&apos;);background-position:39% 79%;background-size:cover;\" class=\"wp-block-group alignfull has-global-padding is-layout-constrained wp-block-group-is-layout-constrained has-background\">\n<div class=\"wp-block-group alignfull is-style-default has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#2429337d;padding-top:var(--wp--preset--spacing--80);padding-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-1542d072 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-bottom:0\">\n<div class=\"wp-block-column is-vertically-aligned-center has-base-color has-text-color has-link-color wp-elements-32d7d339fe44aaa1cb4c6b6a5db2d9b6 is-layout-flow wp-container-core-column-is-layout-93dd39bc wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--30)\">\n<h1 class=\"wp-block-heading has-base-color has-text-color has-link-color has-xx-large-font-size wp-elements-545c00e20bf6c42eb37a7217c512e016\"><strong>\u00dcber uns \u2013 HS Magnet <\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ein f\u00fchrender Permanentmagnethersteller in China<\/strong><\/h2>\n\n\n\n<p class=\"has-base-color has-text-color has-link-color wp-elements-7b28d0cf0f39db8b304d105a73d72a75 wp-block-paragraph\"><a href=\"https:\/\/hsmagnet.com\/de\/\" data-type=\"link\" data-id=\"https:\/\/hsmagnet.com\/\">HS Magnet<\/a> ist ein vertrauensw\u00fcrdiger Permanentmagnethersteller in China, spezialisiert auf die Produktion von Hochleistungs <a href=\"https:\/\/hsmagnet.com\/de\/magnetische-materialien\/ndfeb-magnete\/\" data-type=\"link\" data-id=\"https:\/\/hsmagnet.com\/magnetic-materials\/ndfeb-magnets\/\">Neodym-Magnete (NdFeB)<\/a>, <a href=\"https:\/\/hsmagnet.com\/de\/magnetische-materialien\/smco-magnete\/\" data-type=\"link\" data-id=\"https:\/\/hsmagnet.com\/magnetic-materials\/smco-magnets\/\">Samarium-Kobalt-Magnete (SmCo)<\/a>, <a href=\"https:\/\/hsmagnet.com\/de\/magnetische-materialien\/alnico-magnete\/\" data-type=\"link\" data-id=\"https:\/\/hsmagnet.com\/magnetic-materials\/alnico-magnets\/\">AlNiCo-Magnete<\/a>, <a href=\"https:\/\/hsmagnet.com\/de\/magnetische-materialien\/ferritmagnete\/\" data-type=\"link\" data-id=\"https:\/\/hsmagnet.com\/magnetic-materials\/ferrite-magnets\/\">Ferritmagnete<\/a>, Und <a href=\"https:\/\/hsmagnet.com\/de\/magnetische-materialien\/fecrco-magnet\/\" data-type=\"link\" data-id=\"https:\/\/hsmagnet.com\/magnetic-materials\/fecrco-magnet\/\">FeCrCo-Magnete<\/a>.<br>Mit <strong>\u00fcber 20 Jahre Erfahrung<\/strong>bieten wir kundenspezifische Magnetl\u00f6sungen f\u00fcr Branchen weltweit, von <strong>Motoren<\/strong> Und <strong>Generatoren<\/strong> zu s<strong>Sensoren<\/strong> und medizinische Ger\u00e4te.<\/p>\n\n\n\n<p class=\"has-base-color has-text-color has-link-color wp-elements-0264f4fa753f5360784877bf20680f31 wp-block-paragraph\">Wir sind mehr als eine Produktionsfabrik \u2013 unser Team konzentriert sich auch auf Forschung und Entwicklung und hilft Kunden mit fachkundiger Unterst\u00fctzung bei magnetischen Materialien dabei, vom Prototyp zum fertigen Produkt zu gelangen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-bfoqt83\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-bfoqt83\"><div class=\"eb-wrapper-outer eb-wrapper-bfoqt83\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-b0qy80r\"><div class=\"eb-parent-wrapper eb-parent-eb-row-b0qy80r\"><div class=\"eb-row-root-container eb-row-b0qy80r\" data-id=\"eb-row-b0qy80r\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-v9c51n5\"><div class=\"eb-parent-wrapper eb-parent-eb-column-v9c51n5\"><div class=\"eb-column-wrapper eb-column-v9c51n5\"><div class=\"eb-column-inner\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Wie werden gegossene Alnico-Magnete hergestellt\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Q8f_alzMKr8?start=162&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-oiq2r2g\"><div class=\"eb-parent-wrapper eb-parent-eb-column-oiq2r2g\"><div class=\"eb-column-wrapper eb-column-oiq2r2g\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-wrapper  root-eb-wrapper-qo4ty2x\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-qo4ty2x\"><div class=\"eb-wrapper-outer eb-wrapper-qo4ty2x\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<h2 class=\"wp-block-heading\"><strong>Unsere Geschichte &amp; Historie<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gegr\u00fcndet in <strong>2005<\/strong> und befindet sich in <strong>Bezirk Xiaoshan, Hangzhou<\/strong>, HS Magnet arbeitet nur 4 Kilometer von <strong>Internationaler Flughafen Hangzhou Xiaoshan<\/strong>, wodurch schnelle und zuverl\u00e4ssige weltweite Lieferungen gew\u00e4hrleistet werden.<br>Unsere 20.000 m\u00b2 gro\u00dfe Produktionsst\u00e4tte verf\u00fcgt \u00fcber eine <strong>Jahresumsatz von rund 100 Millionen CNY<\/strong> und beherbergt modernste Fertigungs- und Pr\u00fcfanlagen f\u00fcr eine breite Palette von <strong>Permanentmagnete<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seit dem ersten Tag sind unsere Leitprinzipien:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Kein unqualifiziertes Produkt darf das Werk verlassen<\/strong><br>Diese Verpflichtungen bleiben die Eckpfeiler unseres kontinuierlichen Wachstums.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-3orygky\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-3orygky\"><div class=\"eb-wrapper-outer eb-wrapper-3orygky\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-wrapper  root-eb-wrapper-2108hlv\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-2108hlv\"><div class=\"eb-wrapper-outer eb-wrapper-2108hlv\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-wrapper  root-eb-wrapper-jig0wbs\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-jig0wbs\"><div class=\"eb-wrapper-outer eb-wrapper-jig0wbs\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-8wx5g09\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-8wx5g09 eb_animation eb___animated eb___fadeInUp\"><div class=\"eb-advance-heading-wrapper eb-advance-heading-8wx5g09 button-1 undefined\" data-id=\"eb-advance-heading-8wx5g09\"><h2 class=\"eb-ah-title\"><span class=\"first-title\">Unsere Produkte<\/span><\/h2><\/div><\/div><\/div>\n\n\n\n<p class=\"has-base-color has-text-color has-link-color wp-elements-364baa9c82a8f8955c39c766bc9532eb wp-block-paragraph\">Bei <strong>HS-Magnet,<\/strong> Wir widmen uns der <strong>Design<\/strong>, <strong>Produktion<\/strong>, Und <strong>Verk\u00e4ufe<\/strong> von verschiedenen Permanentmagneten. Unsere Expertise liegt in der Erstellung <strong>Brauch<\/strong> Und <strong>Standard-Magnetl\u00f6sungen<\/strong> ma\u00dfgeschneidert auf Ihre spezifischen Anforderungen. Wir k\u00fcmmern uns um alles, von der ersten Konzeptentwicklung bis zur endg\u00fcltigen Lieferung, und stellen sicher, dass jeder Magnet den h\u00f6chsten Standards entspricht.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-yqt5hq0\"><div class=\"eb-parent-wrapper eb-parent-eb-row-yqt5hq0\"><div class=\"eb-row-root-container eb-row-yqt5hq0\" data-id=\"eb-row-yqt5hq0\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-72zfj47\"><div class=\"eb-parent-wrapper eb-parent-eb-column-72zfj47\"><div class=\"eb-column-wrapper eb-column-72zfj47\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-3wa38\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-3wa38\"><div class=\"eb-infobox-3wa38 eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/alnico-magnets.webp\" alt=\"Alnico-Magnet\"\/><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\">Alnico-Magnet<\/h2><p class=\"description\">Hohe Temperaturbest\u00e4ndigkeit, stabile Leistung<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor infobox-btn\" href=\"\/de\/magnetische-materialien\/alnico-magnete\/\" rel=\"noopener\">Mehr lesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-wxpq89z\"><div class=\"eb-parent-wrapper eb-parent-eb-column-wxpq89z\"><div class=\"eb-column-wrapper eb-column-wxpq89z\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-w4877\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-w4877\"><div class=\"eb-infobox-w4877 eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/NeFeB-magnet.webp\" alt=\"NeFeB-Magnet\"\/><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\">NdFeB-Magnet<\/h2><p class=\"description\">St\u00e4rkste verf\u00fcgbare Magnetkraft, Seltenerdmagnet<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor infobox-btn\" href=\"\/de\/magnetische-materialien\/ndfeb-magnete\/\" rel=\"noopener\">Mehr lesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-9r89xba\"><div class=\"eb-parent-wrapper eb-parent-eb-column-9r89xba\"><div class=\"eb-column-wrapper eb-column-9r89xba\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-oz22r\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-oz22r\"><div class=\"eb-infobox-oz22r eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/Samarium-Cobalt-Magnet.webp\" alt=\"Samarium-Kobalt-Magnet\"\/><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\">SmCo-Magnet<\/h2><p class=\"description\">Hervorragende Temperaturstabilit\u00e4t, starke Magnetkraft, Seltene Erden<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor infobox-btn\" href=\"\/de\/magnetische-materialien\/smco-magnete\/\" rel=\"noopener\">Mehr lesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-rh8dv\"><div class=\"eb-parent-wrapper eb-parent-eb-row-rh8dv\"><div class=\"eb-row-root-container eb-row-rh8dv\" data-id=\"eb-row-rh8dv\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-c4vg5\"><div class=\"eb-parent-wrapper eb-parent-eb-column-c4vg5\"><div class=\"eb-column-wrapper eb-column-c4vg5\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-9hqf1\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-9hqf1\"><div class=\"eb-infobox-9hqf1 eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/FERRITE-MAGNET.webp\" alt=\"FERRITMAGNET\"\/><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\">Ferritmagnet<\/h2><p class=\"description\">Kosteng\u00fcnstig, korrosionsbest\u00e4ndig<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor infobox-btn\" href=\"\/de\/magnetische-materialien\/ferritmagnete\/\" rel=\"noopener\">Mehr lesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-e4y76\"><div class=\"eb-parent-wrapper eb-parent-eb-column-e4y76\"><div class=\"eb-column-wrapper eb-column-e4y76\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-bqugu\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-bqugu\"><div class=\"eb-infobox-bqugu eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/Fecrco-Magnet-with-Thread-for-Guitar-Pickup-Magnet.webp\" alt=\"FeCrCo-Magnet\"\/><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\">FeCrCo-Magnet<\/h2><p class=\"description\">Flexibel formbar und bearbeitbar, Alnico-Alternative<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor infobox-btn\" href=\"\/de\/magnetische-materialien\/fecrco-magnet\/\" rel=\"noopener\">Mehr lesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-xv6mo\"><div class=\"eb-parent-wrapper eb-parent-eb-column-xv6mo\"><div class=\"eb-column-wrapper eb-column-xv6mo\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-74a98\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-74a98\"><div class=\"eb-infobox-74a98 eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/Permanent-magnet-alternator-SC-ROTOR.webp\" alt=\"Permanentmagnet-Generator SC ROTOR\"\/><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\">Magnetbaugruppe<\/h2><p class=\"description\">spezifische Funktionalit\u00e4ten magnetischer Komponenten<\/p><div class=\"eb-button-inner-wrapper eb-infobox-btn-wrapper\"><a class=\"eb-button-anchor infobox-btn\" href=\"\/de\/magnetbaugruppe\/\" rel=\"noopener\">Mehr lesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-x9wo6\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-x9wo6\"><div class=\"eb-wrapper-outer eb-wrapper-x9wo6\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-columns are-vertically-aligned-top is-style-default is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-xx-large-font-size\">Unsere globale Reichweite<\/h2>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"13100\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop3.webp\" alt=\"\" class=\"wp-image-13100\" srcset=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop3.webp 1024w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop3-300x225.webp 300w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop3-768x576.webp 768w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop3-600x450.webp 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"13101\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop2.webp\" alt=\"\" class=\"wp-image-13101\" srcset=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop2.webp 1024w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop2-300x225.webp 300w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop2-768x576.webp 768w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop2-600x450.webp 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"13102\" src=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop-1024x768.webp\" alt=\"\" class=\"wp-image-13102\" srcset=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop-1024x768.webp 1024w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop-300x225.webp 300w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop-768x576.webp 768w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop-600x450.webp 600w, https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/workshop.webp 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-803h68b\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-803h68b\"><div class=\"eb-wrapper-outer eb-wrapper-803h68b\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-jwlceso\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-jwlceso eb_animation eb___animated eb___fadeInLeft\"><div class=\"eb-advance-heading-wrapper eb-advance-heading-jwlceso button-1 undefined\" data-id=\"eb-advance-heading-jwlceso\"><h2 class=\"eb-ah-title\"><span class=\"first-title\">Warum uns w\u00e4hlen?<\/span><\/h2><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Partnerschaft mit HS MAGNET bedeutet, dass Sie Zugang zu un\u00fcbertroffenen Vorteilen in der Permanentmagnetindustrie erhalten:<\/p>\n\n\n\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-2stp9si\"><div class=\"eb-parent-wrapper eb-parent-eb-row-2stp9si\"><div class=\"eb-row-root-container eb-row-2stp9si\" data-id=\"eb-row-2stp9si\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-1ki886e\"><div class=\"eb-parent-wrapper eb-parent-eb-column-1ki886e eb_animation eb___animated eb___fadeInDown\"><div class=\"eb-column-wrapper eb-column-1ki886e\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-ntuceen\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-ntuceen eb_animation eb___animated eb___fadeInUp\"><div class=\"eb-infobox-ntuceen eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-icon number-or-icon\"><span class=\"dashicon dashicons dashicons-yes eb-infobox-icon-data-selector\"><\/span><\/div><\/div><div class=\"contents-wrapper\"><h3 class=\"title\">\u00dcberlegene Produktqualit\u00e4t<\/h3><p class=\"description\">Dank strenger Tests und Qualit\u00e4tssicherung bieten unsere Magnete gleichbleibende Leistung und Langlebigkeit.<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-i1mvg\"><div class=\"eb-parent-wrapper eb-parent-eb-column-i1mvg\"><div class=\"eb-column-wrapper eb-column-i1mvg\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-8dwci\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-8dwci eb_animation eb___animated eb___fadeInUp\"><div class=\"eb-infobox-8dwci eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-icon number-or-icon\"><span class=\"dashicon dashicons dashicons-admin-tools eb-infobox-icon-data-selector\"><\/span><\/div><\/div><div class=\"contents-wrapper\"><h3 class=\"title\">Kundenspezifische L\u00f6sungen<\/h3><p class=\"description\">Wir bieten ma\u00dfgeschneiderte Designs, die genau Ihren Spezifikationen entsprechen, vom kleinen Prototypen bis zur Gro\u00dfserienproduktion.<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-f926w\"><div class=\"eb-parent-wrapper eb-parent-eb-column-f926w\"><div class=\"eb-column-wrapper eb-column-f926w\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-wcoxo\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-wcoxo eb_animation eb___animated eb___fadeInUp\"><div class=\"eb-infobox-wcoxo eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-icon number-or-icon\"><span class=\"dashicon dashicons dashicons-clipboard eb-infobox-icon-data-selector\"><\/span><\/div><\/div><div class=\"contents-wrapper\"><h3 class=\"title\">Wettbewerbsf\u00e4hige Preise<\/h3><p class=\"description\">Profitieren Sie von unseren effizienten Herstellungsprozessen, die die Kosten niedrig halten, ohne die Qualit\u00e4t zu beeintr\u00e4chtigen.<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-gn46z3f\"><div class=\"eb-parent-wrapper eb-parent-eb-column-gn46z3f\"><div class=\"eb-column-wrapper eb-column-gn46z3f\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-8g5kv\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-8g5kv eb_animation eb___animated eb___fadeInUp\"><div class=\"eb-infobox-8g5kv eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-icon number-or-icon\"><span class=\"dashicon dashicons dashicons-airplane eb-infobox-icon-data-selector\"><\/span><\/div><\/div><div class=\"contents-wrapper\"><h3 class=\"title\">Zuverl\u00e4ssige Lieferung<\/h3><p class=\"description\">Durch unsere strategische Lage und unser Logistik-Know-how gew\u00e4hrleisten wir einen schnellen und zuverl\u00e4ssigen Versand weltweit.<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-oyvmxis\"><div class=\"eb-parent-wrapper eb-parent-eb-column-oyvmxis\"><div class=\"eb-column-wrapper eb-column-oyvmxis\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox  root-eb-infobox-iguog\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-iguog eb_animation eb___animated eb___fadeInUp\"><div class=\"eb-infobox-iguog eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-icon number-or-icon\"><span class=\"dashicon dashicons dashicons-admin-users eb-infobox-icon-data-selector\"><\/span><\/div><\/div><div class=\"contents-wrapper\"><h3 class=\"title\">Kundenzentrierter Ansatz<\/h3><p class=\"description\">Dank strenger Tests und Qualit\u00e4tssicherung bieten unsere Magnete gleichbleibende Leistung und Langlebigkeit.<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Diese St\u00e4rken haben uns das Vertrauen zahlloser Kunden eingebracht und HS MAGNET zu einem bevorzugten Lieferanten von Permanentmagneten f\u00fcr Branchen gemacht, die nach Zuverl\u00e4ssigkeit und Innovation suchen.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-ffe1e5eb wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--70);padding-left:var(--wp--preset--spacing--70)\">\n<h2 class=\"wp-block-heading has-xx-large-font-size\"><strong>Unser Zertifikat<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2026\/01\/1.-2025\u5e74\u5ea6\u4f01\u4e1a\u8d28\u91cf\u8bda\u4fe1\u62a5\u544a.pdf\" type=\"link\" id=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2026\/01\/1.-2025\u5e74\u5ea6\u4f01\u4e1a\u8d28\u91cf\u8bda\u4fe1\u62a5\u544a.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">2025\u5e74\u5ea6\u4f01\u4e1a\u8d28\u91cf\u8bda\u4fe1\u62a5\u544a<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2026\/01\/2.-2025\u5e74\u5ea6\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\u62a5\u544a.pdf\" type=\"link\" id=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2026\/01\/2.-2025\u5e74\u5ea6\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\u62a5\u544a.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">2025\u5e74\u5ea6\u4f01\u4e1a\u793e\u4f1a\u8d23\u4efb\u62a5\u544a<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>About Us \u2013 HS Magnet A Leading Permanent Magnet Manufacturer in China HS Magnet is a trusted permanent magnet manufacturer in China, specializing in the production of high-performance Neodymium magnets (NdFeB), Samarium Cobalt magnets (SmCo), AlNiCo magnets, Ferrite magnets, and FeCrCo magnets.With over 20 years of experience, we provide custom magnet solutions for industries worldwide, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-no-title","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"class_list":["post-36","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Magnet Manufacturer - HS Magnet - Neodymium Magnet Alnico<\/title>\n<meta name=\"description\" content=\"HS Magnet is a magnet manufacturer producing permanent magnets. We mainly produce Neodymium magnets SmCo magnet, AlNiCo magnet FeCrCo magnet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hsmagnet.com\/de\/uber-uns\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magnet Manufacturer - HS Magnet - Neodymium Magnet Alnico\" \/>\n<meta property=\"og:description\" content=\"HS Magnet is a magnet manufacturer producing permanent magnets. We mainly produce Neodymium magnets SmCo magnet, AlNiCo magnet FeCrCo magnet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hsmagnet.com\/de\/uber-uns\/\" \/>\n<meta property=\"og:site_name\" content=\"Hangzhou HS Magnet Co.,Ltd.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T02:43:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/alnico-magnets.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/\",\"url\":\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/\",\"name\":\"Magnet Manufacturer - HS Magnet - Neodymium Magnet Alnico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hsmagnet.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/alnico-magnets.webp\",\"datePublished\":\"2021-09-03T01:02:51+00:00\",\"dateModified\":\"2026-01-27T02:43:35+00:00\",\"description\":\"HS Magnet is a magnet manufacturer producing permanent magnets. We mainly produce Neodymium magnets SmCo magnet, AlNiCo magnet FeCrCo magnet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hsmagnet.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/alnico-magnets.webp\",\"contentUrl\":\"https:\\\/\\\/hsmagnet.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/alnico-magnets.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/about-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hsmagnet.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About US\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/#website\",\"url\":\"https:\\\/\\\/hsmagnet.com\\\/\",\"name\":\"Hangzhou HS Magnet Co.,Ltd.\",\"description\":\"Leading manufacturer of premium permanent magnets for industrial applications in china\",\"publisher\":{\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hsmagnet.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/#organization\",\"name\":\"Hangzhou HS Magnet Co.,Ltd.\",\"url\":\"https:\\\/\\\/hsmagnet.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hsmagnet.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo_pc.png\",\"contentUrl\":\"https:\\\/\\\/hsmagnet.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo_pc.png\",\"width\":237,\"height\":64,\"caption\":\"Hangzhou HS Magnet Co.,Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/hsmagnet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Magnethersteller - HS-Magnet - Neodym-Magnet Alnico","description":"HS Magnet ist ein Magnethersteller, der Permanentmagnete herstellt. Wir produzieren haupts\u00e4chlich Neodym-Magnete, SmCo-Magnete, AlNiCo-Magnete und FeCrCo-Magnete.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hsmagnet.com\/de\/uber-uns\/","og_locale":"de_DE","og_type":"article","og_title":"Magnet Manufacturer - HS Magnet - Neodymium Magnet Alnico","og_description":"HS Magnet is a magnet manufacturer producing permanent magnets. We mainly produce Neodymium magnets SmCo magnet, AlNiCo magnet FeCrCo magnet.","og_url":"https:\/\/hsmagnet.com\/de\/uber-uns\/","og_site_name":"Hangzhou HS Magnet Co.,Ltd.","article_modified_time":"2026-01-27T02:43:35+00:00","og_image":[{"url":"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/alnico-magnets.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hsmagnet.com\/about-us\/","url":"https:\/\/hsmagnet.com\/about-us\/","name":"Magnethersteller - HS-Magnet - Neodym-Magnet Alnico","isPartOf":{"@id":"https:\/\/hsmagnet.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hsmagnet.com\/about-us\/#primaryimage"},"image":{"@id":"https:\/\/hsmagnet.com\/about-us\/#primaryimage"},"thumbnailUrl":"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/alnico-magnets.webp","datePublished":"2021-09-03T01:02:51+00:00","dateModified":"2026-01-27T02:43:35+00:00","description":"HS Magnet ist ein Magnethersteller, der Permanentmagnete herstellt. Wir produzieren haupts\u00e4chlich Neodym-Magnete, SmCo-Magnete, AlNiCo-Magnete und FeCrCo-Magnete.","breadcrumb":{"@id":"https:\/\/hsmagnet.com\/about-us\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hsmagnet.com\/about-us\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hsmagnet.com\/about-us\/#primaryimage","url":"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/alnico-magnets.webp","contentUrl":"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/alnico-magnets.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/hsmagnet.com\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hsmagnet.com\/"},{"@type":"ListItem","position":2,"name":"About US"}]},{"@type":"WebSite","@id":"https:\/\/hsmagnet.com\/#website","url":"https:\/\/hsmagnet.com\/","name":"Hangzhou HS Magnet Co., Ltd.","description":"F\u00fchrender Hersteller von Premium-Permanentmagneten f\u00fcr industrielle Anwendungen in China","publisher":{"@id":"https:\/\/hsmagnet.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hsmagnet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hsmagnet.com\/#organization","name":"Hangzhou HS Magnet Co., Ltd.","url":"https:\/\/hsmagnet.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hsmagnet.com\/#\/schema\/logo\/image\/","url":"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/logo_pc.png","contentUrl":"https:\/\/hsmagnet.com\/wp-content\/uploads\/2025\/08\/logo_pc.png","width":237,"height":64,"caption":"Hangzhou HS Magnet Co.,Ltd."},"image":{"@id":"https:\/\/hsmagnet.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/pages\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":40,"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/pages\/36\/revisions"}],"predecessor-version":[{"id":14607,"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/pages\/36\/revisions\/14607"}],"wp:attachment":[{"href":"https:\/\/hsmagnet.com\/de\/wp-json\/wp\/v2\/media?parent=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}